{"id":196143,"date":"2026-07-23T15:21:53","date_gmt":"2026-07-23T13:21:53","guid":{"rendered":"https:\/\/factorialhr.com\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/"},"modified":"2026-07-23T15:21:53","modified_gmt":"2026-07-23T13:21:53","slug":"equilibrio-tra-vita-e-lavoro","status":"publish","type":"factorial_video","link":"https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/","title":{"rendered":"Equilibrio tra vita e lavoro"},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_video_type":"highlight","_related_series":192403,"_related_episode":196125,"_related_season":0,"_video_source":"vimeo","_youtube_video_id":"","_vimeo_video_id":"1205426736","_speaker_id":196124,"_video_description":"Secondo Patrick Vincent e Oriana Cardona, lo sviluppo dell'intelligenza emotiva e adattiva in ambienti ad alta pressione, come l'aviazione e il management, avviene efficacemente attraverso l'esempio. I leader devono essere consapevoli del loro impatto sulle persone, poich\u00e9 le emozioni giocano un ruolo cruciale nell'adattamento alle situazioni. Imparare per imitazione \u00e8 fondamentale: i valori aziendali e una comunicazione chiara sono centrali nella gestione del team e nel piano di carriera di ogni individuo. Favorire l'intelligenza collettiva e promuovere un ambiente di apprendimento continuo permette di plasmare professionisti competenti e consapevoli. Non perdere altri suggerimenti e approfondimenti su come migliorare la leadership e la gestione del team nel video completo.","_video_transcription":"00:09 - Domanda due.Come pilota o manager, come si sviluppa l'intelligenza emotiva e adattiva in un ambiente sotto pressione?\n00:16 - Risposta A: attraverso l'esempio.B: attraverso la formazione.\n00:20 - C: attraverso l'esperienza.D: il jolly.Allora, in questa, c'\u00e8 una risposta che mi piace molto e che cerco di applicare nel mio quotidiano,ed \u00e8: leading by example.\n00:35 - Scelgo la A: attraverso l'esempio.Le prime tre sono tutte vere, ma scelgo il jolly.\n00:41 - Parlate di come si pu\u00f2 fare tutto questo all'interno di un'attivit\u00e0.\n00:47 - Perch\u00e9 ho scelto il jolly per questa dimensione dell'intelligenza emotiva adattiva? Per me \u00e8 la stessa cosa.\n00:53 - Gli ambienti tecnici in cui opero \u2014 \u00e8 meglio parlare di intelligenza adattiva, perch\u00e9 quando si parla di emozione, \u00e8 come se ci fosse un piccolo tab\u00f9 intorno al tema dell'emozione.\n01:04 - Ma siamo esseri emotivi e un'emozione ci serve per adattarci.\n01:09 - Per\u00f2 siamo cresciuti in ambienti che ci hanno portato a codificare le nostre emozioni \u2014 e cos\u00ec le mettiamo sotto il tappeto.\n01:14 - Ma quando si ha un'emozione sotto il tappeto, si inciampa nel tappeto.\n01:17 - L'idea \u00e8 quindi davvero capire che un'emozione ha una funzione.\u00c8 l\u00ec per dirci che dobbiamo adattarci a una situazione.\n01:24 - Quindi, se la mettiamo sotto il tappeto, perdiamo l'occasione di capire il bisogno che si nasconde dietro all'emozione.\n01:29 - Perch\u00e9 ho preso il jolly?Perch\u00e9 ovviamente esistono formazioni per sviluppare l'intelligenza emotiva, l'intelligenza adattiva.\n01:37 - Ci sono molte cose che si possono fare.Ma quello che voglio dire \u00e8 che la cosa pi\u00f9 efficace \u00e8 ci\u00f2 che si fa ogni giorno.\u00c8 ci\u00f2 che si integra nella propria routine quotidiana a fare s\u00ec che si diventi un apprendista permanente di s\u00e9 stessi.\n01:50 - E nell'aviazione, quasi intuitivamente \u2014 senza averlo necessariamente concettualizzato \u2014 abbiamo messo in atto degli strumenti che sono degli spazi-tempo dedicati a prendere distanza, ad animare l'intelligenza collettiva, per poi prendere una decisione, agire, anticipare, rileggere.\n02:09 - La maggior parte dei manager con cui mi interfaccio o che incontro sono diventati manager per le circostanze.\n02:15 - Come dicevamo poco fa: sei molto bravo operativamente,quindi diventi manager \u2014 ma non hai necessariamente tutto ci\u00f2 che riguarda la conoscenza di s\u00e9.\n02:21 - Per me, gli esseri umani imparano per imitazione \u2014 e trovo molto bello questo nel concetto di: si vede, si ammira.\n02:28 - Ci sono persone che hanno segnato e plasmato la nostra vita, e cerchiamo di assomigliare a quella persona.\n02:33 - C'\u00e8 anche qualcosa di molto importante in questo aspetto dell'esempio:il fatto che quell'esempio possa essere positivo o negativo, e che la consapevolezza di un manager nel suo ruolo e l'opinione, l'impatto che avr\u00e0 sulle persone che gestir\u00e0, deve essere molto grande perch\u00e9 plasmeremo le persone, plasmeremo il professionista, plasmeremo delle vite in un certo senso.\n02:54 - Passiamo molto tempo al lavoro.Particolarmente attraverso l'esempio, perch\u00e9 mi baso sulle mie esperienze passate.\n03:04 - Penso che come esseri umani impariamo gi\u00e0 per imitazione.\n03:07 - Fin da bambini, una lingua la impariamo per imitazione.\n03:10 - Non studiamo la grammatica in modo esplicito \u2014 non diciamo al bambino:non hai coniugato bene i verbi.\u00c8 davvero imitazione.\n03:17 - Per me, come essere umano, impariamo per imitazione \u2014 e trovo molto bello questo nel concetto di: si vede, si ammira.\n03:24 - Ci sono persone che hanno segnato e plasmato la nostra vita, e cerchiamo di assomigliare a quella persona.\n03:29 - C'\u00e8 anche qualcosa di molto importante in questo aspetto dell'esempio:il fatto che quell'esempio possa essere positivo o negativo, e che la consapevolezza di un manager nel suo ruolo di manager e l'opinione, l'impatto che avr\u00e0 sulle persone che gestir\u00e0 deve essere molto significativa perch\u00e9 plasmeremo le persone, plasmeremo i professionisti, plasmeremo delle vite in un certo senso.\n03:50 - Passiamo molto tempo al lavoro.Domanda tre.Negli ambienti ad alta responsabilit\u00e0 come l'aviazione o il management, quale fattore di performance \u00e8 ancora troppo spesso sottovalutato oggi?","_has_trailer":false,"_trailer_vimeo_id":"","_trailer_youtube_id":"","_video_duration":"","_video_thumbnail":""},"categories":[961],"factorial-categories":[],"class_list":["post-196143","factorial_video","type-factorial_video","status-publish","hentry","category-gestione-dei-flussi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.9.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Equilibrio tra vita e lavoro | Factorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equilibrio tra vita e lavoro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"Factorial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/factorial.it\/wp-content\/uploads\/2025\/11\/17131146\/factorial-open-graph.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@factorialapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/\",\"url\":\"https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/\",\"name\":\"Equilibrio tra vita e lavoro | Factorial\",\"isPartOf\":{\"@id\":\"https:\/\/factorial.it\/blog\/#website\"},\"datePublished\":\"2026-07-23T13:21:53+00:00\",\"dateModified\":\"2026-07-23T13:21:53+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/factorial.it\/blog\/#website\",\"url\":\"https:\/\/factorial.it\/blog\/\",\"name\":\"Factorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/factorial.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/factorial.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/factorial.it\/blog\/#organization\",\"name\":\"All-in-one business management software - Factorial\",\"url\":\"https:\/\/factorial.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/factorial.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/factorial.it\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"contentUrl\":\"https:\/\/factorial.it\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"width\":946,\"height\":880,\"caption\":\"All-in-one business management software - Factorial\"},\"image\":{\"@id\":\"https:\/\/factorial.it\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\",\"https:\/\/twitter.com\/factorialapp\",\"https:\/\/www.linkedin.com\/company\/factorialhr\",\"https:\/\/www.youtube.com\/@factorialmedia\",\"https:\/\/www.instagram.com\/factorial\/#\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Equilibrio tra vita e lavoro | Factorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/","og_locale":"it_IT","og_type":"article","og_title":"Equilibrio tra vita e lavoro","og_url":"https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/","og_site_name":"Factorial","article_publisher":"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","og_image":[{"width":1200,"height":628,"url":"https:\/\/factorial.it\/wp-content\/uploads\/2025\/11\/17131146\/factorial-open-graph.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@factorialapp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/","url":"https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/","name":"Equilibrio tra vita e lavoro | Factorial","isPartOf":{"@id":"https:\/\/factorial.it\/blog\/#website"},"datePublished":"2026-07-23T13:21:53+00:00","dateModified":"2026-07-23T13:21:53+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/factorial.it\/blog\/factorial-play\/videos\/equilibrio-tra-vita-e-lavoro\/"]}]},{"@type":"WebSite","@id":"https:\/\/factorial.it\/blog\/#website","url":"https:\/\/factorial.it\/blog\/","name":"Factorial","description":"","publisher":{"@id":"https:\/\/factorial.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/factorial.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/factorial.it\/blog\/#organization","name":"All-in-one business management software - Factorial","url":"https:\/\/factorial.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/factorial.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/factorial.it\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","contentUrl":"https:\/\/factorial.it\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","width":946,"height":880,"caption":"All-in-one business management software - Factorial"},"image":{"@id":"https:\/\/factorial.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","https:\/\/twitter.com\/factorialapp","https:\/\/www.linkedin.com\/company\/factorialhr","https:\/\/www.youtube.com\/@factorialmedia","https:\/\/www.instagram.com\/factorial\/#"]}]}},"_links":{"self":[{"href":"https:\/\/factorial.it\/blog\/wp-json\/wp\/v2\/factorial-videos\/196143"}],"collection":[{"href":"https:\/\/factorial.it\/blog\/wp-json\/wp\/v2\/factorial-videos"}],"about":[{"href":"https:\/\/factorial.it\/blog\/wp-json\/wp\/v2\/types\/factorial_video"}],"wp:attachment":[{"href":"https:\/\/factorial.it\/blog\/wp-json\/wp\/v2\/media?parent=196143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/factorial.it\/blog\/wp-json\/wp\/v2\/categories?post=196143"},{"taxonomy":"factorial_category","embeddable":true,"href":"https:\/\/factorial.it\/blog\/wp-json\/wp\/v2\/factorial-categories?post=196143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}